{"id":3443,"date":"2020-11-13T13:32:33","date_gmt":"2020-11-13T12:32:33","guid":{"rendered":"https:\/\/elparking.com\/blog\/?p=3443"},"modified":"2020-11-13T13:42:56","modified_gmt":"2020-11-13T12:42:56","slug":"reformas-legales-para-disminuir-los-accidentes-de-trafico","status":"publish","type":"post","link":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico","title":{"rendered":"Reformas legales para disminuir los accidentes de tr\u00e1fico"},"content":{"rendered":"<p><span style=\"font-family: geomanist-regular;\">Este pasado martes 10 de noviembre, el Consejo de Ministros ha aprobado <strong>un paquete de nuevas normas legales<\/strong> con el objetivo de reducir en un 50 por ciento los fallecidos y heridos graves producidos en las carreteras durante la pr\u00f3xima d\u00e9cada. En el post de hoy, os contamos cuales ser\u00e1n los principales cambios para disminuir los accidentes de tr\u00e1fico y c\u00f3mo nos afectar\u00edan a nuestros puntos del carn\u00e9 de conducir.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3456\" title=\"reforma legal, accidentes trafico, punto del carne\" src=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2.jpg\" alt=\"reforma legal, accidentes trafico, punto del carne\" width=\"678\" height=\"339\" srcset=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2.jpg 1024w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2-300x150.jpg 300w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2-768x384.jpg 768w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/><\/p>\n<p><span style=\"font-family: geomanist-regular;\">Este nuevo paquete de reformas legales, siempre acorde a lo establecido por la Organizaci\u00f3n Mundial de la Salud y alineado con la pol\u00edtica de la Uni\u00f3n Europea, engloba diferentes medidas que afectan a la reforma de la Ley sobre Tr\u00e1fico, Circulaci\u00f3n de veh\u00edculos a motor y a la Seguridad.<\/span><\/p>\n<p><span style=\"font-family: geomanist-regular;\">Dicho de otro modo, <strong>este nuevo modelo de seguridad vial, modificar\u00e1 de manera sustancial la legislaci\u00f3n del tr\u00e1fico y circulaci\u00f3n.\u00a0<\/strong><\/span><\/p>\n<p><span style=\"font-family: geomanist-regular;\">\u00bfCu\u00e1les son esas medidas?<\/span><\/p>\n<p><span style=\"font-family: geomanist-regular;\">En primer lugar, la reforma afectar\u00e1 a todos aquellos comportamientos que tengamos los conductores considerados m\u00e1s peligrosos, como ser\u00eda coger el m\u00f3vil mientras conducimos o no llevar el casco. <\/span><\/p>\n<p><span style=\"font-family: geomanist-regular;\">Entre las nuevas medidas destacan:<\/span><\/p>\n<ul>\n<li><span style=\"font-family: geomanist-regular;\"><strong>Aumento de 3 a 6 puntos de retirada<\/strong> del carn\u00e9 por conducir sosteniendo con la mano cualquier tipo de dispositivo m\u00f3vil.<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3462 size-full\" title=\"movil, dispositivo movil, puntos carne de conducir, accidentes de trafico\" src=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/1.jpg\" alt=\"movil, dispositivo movil, puntos carne de conducir\" width=\"1024\" height=\"512\" srcset=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/1.jpg 1024w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/1-300x150.jpg 300w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/1-768x384.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<ul>\n<li><span style=\"font-family: geomanist-regular;\"><strong>Aumento de 3 a 4 puntos a detraer<\/strong> por no utilizar el cintur\u00f3n de seguridad, sistemas de retenci\u00f3n infantil, el casco y otros sistemas de protecci\u00f3n.<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3464 size-full\" title=\"cinturon seguridad, puntos carne de conducir, accidentes de trafico\" src=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/2.jpg\" alt=\"cinturon seguridad, puntos carne de conducir\" width=\"1024\" height=\"512\" srcset=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/2.jpg 1024w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/2-300x150.jpg 300w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/2-768x384.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<ul>\n<li><span style=\"font-family: geomanist-regular;\"><strong>P\u00e9rdida de 3 puntos por la tenencia<\/strong> de mecanismos de detecci\u00f3n de radares o similar, suponiendo adem\u00e1s una sanci\u00f3n de 500\u20ac. Si antes la multa habr\u00eda sido impuesta por tener el sistema anti-radar activo, ahora ser\u00eda por el simple hecho de tenerlo en el coche aunque no estuviese operativo en ese momento.<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3465 size-full\" title=\"sistema antiradar, puntos carne de conducir, accidentes de trafico\" src=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/3-2.jpg\" alt=\"sistema antiradar, puntos carne de conducir, accidentes de trafico\" width=\"1024\" height=\"512\" srcset=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/3-2.jpg 1024w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/3-2-300x150.jpg 300w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/3-2-768x384.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<ul>\n<li><span style=\"font-family: geomanist-regular;\">Como ya ocurri\u00f3 en el resto de pa\u00edses de la Uni\u00f3n Europea, <strong>se suprime la posibilidad de aumentar en 20km\/h<\/strong> los l\u00edmites de velocidad para realizar un adelantamiento.<\/span><\/li>\n<li><span style=\"font-family: geomanist-regular;\">Para quien lo quiera, <strong>se podr\u00e1 recuperar 2 puntos del carn\u00e9 de conducir<\/strong> realizando los cursos de la Direcci\u00f3n General de Tr\u00e1fico.<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3466 size-full\" title=\"cursos DGT, direccion general trafico, puntos carne de conducir, accidentes de trafico\" src=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/4-1.jpg\" alt=\"cursos DGT, direccion general trafico, puntos carne de conducir, accidentes de trafico\" width=\"1024\" height=\"512\" srcset=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/4-1.jpg 1024w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/4-1-300x150.jpg 300w, https:\/\/elparking.com\/blog\/wp-content\/uploads\/4-1-768x384.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<ul>\n<li><span style=\"font-family: geomanist-regular;\">Dos a\u00f1os ser\u00e1 el <strong>nuevo plazo para poder recuperar el total inicial de puntos<\/strong> (tiempo que ahora var\u00eda en funci\u00f3n de la\/s infracci\u00f3n\/es cometidas).<\/span><\/li>\n<li><span style=\"font-family: geomanist-regular;\"><strong>Sanci\u00f3n de 500\u20ac y penalizaci\u00f3n de 6 meses<\/strong> sin poder presentarse al examen del carn\u00e9 de conducir a aquellos que utilicen sistemas de intercomunicaci\u00f3n no autorizados durante la prueba.<\/span><\/li>\n<li><span style=\"font-family: geomanist-regular;\">Las empresas de transporte de personas y\/o mercanc\u00edas podr\u00e1n comprobar de forma online si sus trabajadores tienen su <strong>permiso de conducir en vigor<\/strong>.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-family: geomanist-regular;\">En segundo lugar, <strong>el objetivo es reducir la siniestralidad en el ambiente urbano<\/strong>, por lo que el Consejo de Ministros ha aprobado un Real Decreto que define los nuevos l\u00edmites generales de velocidad en v\u00edas urbanas:<\/span><\/p>\n<ul>\n<li><span style=\"font-family: geomanist-regular;\"><strong>30 km\/h<\/strong> en v\u00edas de un \u00fanico carril por sentido de circulaci\u00f3n.<\/span><\/li>\n<li><span style=\"font-family: geomanist-regular;\"><strong>50 km\/h<\/strong> en v\u00edas de 2 o m\u00e1s carriles por sentido.<\/span><\/li>\n<li><span style=\"font-family: geomanist-regular;\"><strong>20 km\/h<\/strong> en v\u00edas que tengan plataforma \u00fanica de calzada.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-family: geomanist-regular;\"><strong>En cuanto a los veh\u00edculos de movilidad personal<\/strong>, definidos como <em>veh\u00edculos de una o m\u00e1s ruedas dotados de una \u00fanica plaza y propulsados exclusivamente por motores el\u00e9ctricos que pueden proporcionar al veh\u00edculo una velocidad m\u00e1xima comprendida entre 6 y 25 km\/h<\/em>, tendr\u00e1n que cumplir las normas de circulaci\u00f3n como el resto de veh\u00edculos quedando prohibida su circulaci\u00f3n en v\u00edas interurbanas, traves\u00edas, as\u00ed como autopistas y autov\u00edas que transcurran dentro de poblado ni en t\u00faneles urbanos. <\/span><\/p>\n<p><span style=\"font-family: geomanist-regular;\">En \u00faltimo lugar, el Consejo de Ministros ha aprobado un real decreto que <strong>reforma el Reglamento General de Conductores sobre el permiso de conducci\u00f3n<\/strong>. Estas ser\u00edan algunas de sus nuevas medidas:\u00a0<\/span><\/p>\n<ul>\n<li><span style=\"font-family: geomanist-regular;\"><strong>Reducci\u00f3n de 21 a 18 a\u00f1os<\/strong> la edad m\u00ednima exigible para conducir camiones.\u00a0<\/span><\/li>\n<li><span style=\"font-family: geomanist-regular;\"><strong>Reducci\u00f3n de 21 a 18 a\u00f1os<\/strong> la edad m\u00ednima exigible para conducir autocares, pero en este caso, deber\u00e1 circularse solo sin pasajeros y en un radio m\u00e1ximo de 50km. <\/span><\/li>\n<li><span style=\"font-family: geomanist-regular;\">Como medida para favorecer el uso de combustibles alternativos no contaminantes, <strong>se ampl\u00eda de 3.500 a 4.250kg el peso de las furgonetas<\/strong> que se pueden conducir en territorio nacional con el permiso B para el transporte de mercanc\u00edas solo cuando ese incremento de peso se deba a los nuevos sistemas de propulsi\u00f3n. <\/span><\/li>\n<\/ul>\n<p><span style=\"font-family: geomanist-regular;\">Y bien, \u00bfcu\u00e1ndo entrar\u00e1n en vigor estas medidas que nos afectar\u00e1n a todos los conductores? <\/span><\/p>\n<p><span style=\"font-family: geomanist-regular;\">Estas modificaciones del Reglamento de Circulaci\u00f3n y Veh\u00edculos, entrar\u00e1n en vigor el <strong>pr\u00f3ximo 2 de enero del 2021. <\/strong><\/span><\/p>\n<p><span style=\"font-family: geomanist-regular;\">Sin embargo, la modificaci\u00f3n del art\u00edculo 50 del Reglamento General de Circulaci\u00f3n -la que afecta a los l\u00edmites de velocidad en zonas urbanas-, no se aplicar\u00e1n hasta <strong>pasados 6 meses de la publicaci\u00f3n de este proyecto en el Bolet\u00edn Oficial del Estado<\/strong> para que haya tiempo suficiente para incorporar la nueva se\u00f1alizaci\u00f3n y para que los conductores y ciudadanos podamos conocerlas de forma adecuada.<\/span><\/p>\n<p><span style=\"font-family: geomanist-regular;\">\u00bfQuieres estar al tanto de tus puntos de carn\u00e9 y multas? Conoce <a href=\"https:\/\/elparking.com\/conductor-plus\">conductor plus<\/a>.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este pasado martes 10 de noviembre, el Consejo de Ministros ha aprobado un paquete de nuevas normas legales con el objetivo de reducir en un 50 por ciento los fallecidos y heridos graves producidos en las carreteras durante la pr\u00f3xima d\u00e9cada. En el post de hoy, os contamos cuales ser\u00e1n los principales cambios para disminuir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3443","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reformas legales para disminuir los accidentes de tr\u00e1fico<\/title>\n<meta name=\"description\" content=\"Reformas legales para disminuir los accidentes de tr\u00e1fico que modificar\u00e1n de manera sustancial la legislaci\u00f3n del tr\u00e1fico y circulaci\u00f3n.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reformas legales para disminuir los accidentes de tr\u00e1fico\" \/>\n<meta property=\"og:description\" content=\"Reformas legales para disminuir los accidentes de tr\u00e1fico que modificar\u00e1n de manera sustancial la legislaci\u00f3n del tr\u00e1fico y circulaci\u00f3n.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico\" \/>\n<meta property=\"og:site_name\" content=\"El blog de ElParking\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/elparkingapp\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-13T12:32:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-13T12:42:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2.jpg\" \/>\n<meta name=\"author\" content=\"ElParking Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elparkingapp\" \/>\n<meta name=\"twitter:site\" content=\"@elparkingapp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ElParking Blog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico\"},\"author\":{\"name\":\"ElParking Blog\",\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/#\\\/schema\\\/person\\\/3cbb1ef55e8427a7bf1967dc065112f1\"},\"headline\":\"Reformas legales para disminuir los accidentes de tr\u00e1fico\",\"datePublished\":\"2020-11-13T12:32:33+00:00\",\"dateModified\":\"2020-11-13T12:42:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico\"},\"wordCount\":866,\"image\":{\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elparking.com\\\/blog\\\/wp-content\\\/uploads\\\/blog-2.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico\",\"url\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico\",\"name\":\"Reformas legales para disminuir los accidentes de tr\u00e1fico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elparking.com\\\/blog\\\/wp-content\\\/uploads\\\/blog-2.jpg\",\"datePublished\":\"2020-11-13T12:32:33+00:00\",\"dateModified\":\"2020-11-13T12:42:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/#\\\/schema\\\/person\\\/3cbb1ef55e8427a7bf1967dc065112f1\"},\"description\":\"Reformas legales para disminuir los accidentes de tr\u00e1fico que modificar\u00e1n de manera sustancial la legislaci\u00f3n del tr\u00e1fico y circulaci\u00f3n.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico#primaryimage\",\"url\":\"https:\\\/\\\/elparking.com\\\/blog\\\/wp-content\\\/uploads\\\/blog-2.jpg\",\"contentUrl\":\"https:\\\/\\\/elparking.com\\\/blog\\\/wp-content\\\/uploads\\\/blog-2.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/reformas-legales-para-disminuir-los-accidentes-de-trafico#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elparking.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reformas legales para disminuir los accidentes de tr\u00e1fico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/elparking.com\\\/blog\\\/\",\"name\":\"El blog de ElParking\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elparking.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elparking.com\\\/blog\\\/#\\\/schema\\\/person\\\/3cbb1ef55e8427a7bf1967dc065112f1\",\"name\":\"ElParking Blog\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reformas legales para disminuir los accidentes de tr\u00e1fico","description":"Reformas legales para disminuir los accidentes de tr\u00e1fico que modificar\u00e1n de manera sustancial la legislaci\u00f3n del tr\u00e1fico y circulaci\u00f3n.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico","og_locale":"es_ES","og_type":"article","og_title":"Reformas legales para disminuir los accidentes de tr\u00e1fico","og_description":"Reformas legales para disminuir los accidentes de tr\u00e1fico que modificar\u00e1n de manera sustancial la legislaci\u00f3n del tr\u00e1fico y circulaci\u00f3n.\u00a0","og_url":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico","og_site_name":"El blog de ElParking","article_publisher":"https:\/\/facebook.com\/elparkingapp","article_published_time":"2020-11-13T12:32:33+00:00","article_modified_time":"2020-11-13T12:42:56+00:00","og_image":[{"url":"https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2.jpg","type":"","width":"","height":""}],"author":"ElParking Blog","twitter_card":"summary_large_image","twitter_creator":"@elparkingapp","twitter_site":"@elparkingapp","twitter_misc":{"Escrito por":"ElParking Blog","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico#article","isPartOf":{"@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico"},"author":{"name":"ElParking Blog","@id":"https:\/\/elparking.com\/blog\/#\/schema\/person\/3cbb1ef55e8427a7bf1967dc065112f1"},"headline":"Reformas legales para disminuir los accidentes de tr\u00e1fico","datePublished":"2020-11-13T12:32:33+00:00","dateModified":"2020-11-13T12:42:56+00:00","mainEntityOfPage":{"@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico"},"wordCount":866,"image":{"@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico#primaryimage"},"thumbnailUrl":"https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico","url":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico","name":"Reformas legales para disminuir los accidentes de tr\u00e1fico","isPartOf":{"@id":"https:\/\/elparking.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico#primaryimage"},"image":{"@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico#primaryimage"},"thumbnailUrl":"https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2.jpg","datePublished":"2020-11-13T12:32:33+00:00","dateModified":"2020-11-13T12:42:56+00:00","author":{"@id":"https:\/\/elparking.com\/blog\/#\/schema\/person\/3cbb1ef55e8427a7bf1967dc065112f1"},"description":"Reformas legales para disminuir los accidentes de tr\u00e1fico que modificar\u00e1n de manera sustancial la legislaci\u00f3n del tr\u00e1fico y circulaci\u00f3n.\u00a0","breadcrumb":{"@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico#primaryimage","url":"https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2.jpg","contentUrl":"https:\/\/elparking.com\/blog\/wp-content\/uploads\/blog-2.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/elparking.com\/blog\/reformas-legales-para-disminuir-los-accidentes-de-trafico#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elparking.com\/blog"},{"@type":"ListItem","position":2,"name":"Reformas legales para disminuir los accidentes de tr\u00e1fico"}]},{"@type":"WebSite","@id":"https:\/\/elparking.com\/blog\/#website","url":"https:\/\/elparking.com\/blog\/","name":"El blog de ElParking","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elparking.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/elparking.com\/blog\/#\/schema\/person\/3cbb1ef55e8427a7bf1967dc065112f1","name":"ElParking Blog"}]}},"_links":{"self":[{"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/posts\/3443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/comments?post=3443"}],"version-history":[{"count":26,"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/posts\/3443\/revisions"}],"predecessor-version":[{"id":3475,"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/posts\/3443\/revisions\/3475"}],"wp:attachment":[{"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/media?parent=3443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/categories?post=3443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elparking.com\/blog\/wp-json\/wp\/v2\/tags?post=3443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}